{"id":11534,"date":"2021-02-24T10:41:00","date_gmt":"2021-02-24T09:41:00","guid":{"rendered":"https:\/\/oes.fundacion-sm.org\/noticias\/valores-ecologicos-entre-los-jovenes-informe-jovenes-espanoles-2021\/"},"modified":"2023-09-20T12:51:31","modified_gmt":"2023-09-20T10:51:31","slug":"valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021","status":"publish","type":"post","link":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/","title":{"rendered":"Valores ecol\u00f3gicos entre os jovens. Relat\u00f3rio Jovens Espanh\u00f3is 2021"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11534\" class=\"elementor elementor-11534 elementor-1134\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56e2905 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"56e2905\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6438b0b\" data-id=\"6438b0b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9044f8 elementor-widget elementor-widget-bloque-texto\" data-id=\"e9044f8\" data-element_type=\"widget\" data-widget_type=\"bloque-texto.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- Texto -->\n<section class=\"bloque bloque-texto  \">\n    <div class=\"container\">\n        <div class=\"estrecho2\">\n            \n            <div class=\"row\">\n                <div class=\"col-sm-12\">\n                    <div class=\"the_content\" data-aos=\"fade-up\" data-aos-duration=\"700\">\n                        <p>O relat\u00f3rio <em>Jovens Espanh\u00f3is 2005 <\/em>da <a href=\"https:\/\/fundacion-sm.org\/pt-br\/\" target=\"_blank\" rel=\"noopener\">Funda\u00e7\u00e3o SM<\/a> foi o pioneiro na introdu\u00e7\u00e3o de uma quest\u00e3o que naquela \u00e9poca parecia importar a muito poucos, mas que hoje, depois de d\u00e9cadas de advert\u00eancias desatendidas das mais altas organiza\u00e7\u00f5es internacionais e ONG ao redor do mundo, acabou ocupando finalmente o centro do cen\u00e1rio sociopol\u00edtico global: os valores e a consci\u00eancia ambientais.<\/p>\n<p>Diante dessa <em>irresponsabilidade <\/em>organizada, termo cunhado por Ulrich Beck no in\u00edcio da d\u00e9cada de 1990, surgiram nos \u00faltimos anos in\u00fameros grupos juvenis como Fridays For Future, Juventud Por El Clima e Extinction Rebellion, com os temas imperantes de <em>consci\u00eancia ambiental<\/em>, originalmente um quadro anal\u00edtico pelo qual se pretende conhecer a intensidade e a forma com que os cidad\u00e3os se relacionam com o meio ambiente, assim como a <em>participa\u00e7\u00e3o ambiental <\/em>como modelo concreto de responsabilidade moral para com a natureza.<\/p>\n<p>Uma explora\u00e7\u00e3o do quadro social mais amplo em que ocorrem as diversas mudan\u00e7as de atitudes em nosso pa\u00eds nos aponta que, no entanto, essa transforma\u00e7\u00e3o n\u00e3o \u00e9 protagonizada apenas pelos jovens. Quando realizamos esta an\u00e1lise para a sociedade espanhola, encontramos no relat\u00f3rio de 2010 uma cidadania que apresentava taxas muito inferiores \u00e0s do resto da Europa em praticamente todas as dimens\u00f5es abordadas (Gonz\u00e1lez-Anleo, 2010, p. 32 e ss.). Dez anos depois, o quadro geral da sociedade espanhola \u00e9 muito diferente. V\u00e1rios relat\u00f3rios da Comiss\u00e3o Europeia proporcionam dados nesse sentido que h\u00e1 apenas uma d\u00e9cada teriam parecido simplesmente incr\u00edveis. Foco em dois deles:<\/p>\n<ul>\n<li>Em apenas dois anos, um forte aumento no n\u00famero de espanh\u00f3is que consideram as mudan\u00e7as clim\u00e1ticas como o problema \u201cmais importante\u201d que a humanidade deve enfrentar. Um avan\u00e7o coloca a Espanha, em 2020, \u00e0 frente de todos os pa\u00edses europeus em considerar esse fen\u00f4meno como \u201cum problema muito s\u00e9rio\u201d (European Commission, 2020, p. 12 e ss.).<\/li>\n<li>Um incremento equivalente daqueles cidad\u00e3os que \u201cpessoalmente\u201d consideram \u201cmuito importante\u201d a prote\u00e7\u00e3o do meio ambiente, 10% acima da m\u00e9dia europeia e bem \u00e0 frente no que se refere \u00e0 preocupa\u00e7\u00e3o com diferentes quest\u00f5es, como \u201cpolui\u00e7\u00e3o do ar\u201d, \u201cpolui\u00e7\u00e3o marinha\u201d ou a polui\u00e7\u00e3o de \u201crios, lagos ou \u00e1guas subterr\u00e2neas\u201d etc. (p. 21).<\/li>\n<\/ul>\n<p>Os dados do \u00faltimo relat\u00f3rio da Funda\u00e7\u00e3o SM, <a href=\"https:\/\/oji.fundacion-sm.org\/presentacion-del-informe-jovenes-espanoles-2021\/\" target=\"_blank\" rel=\"noopener\"><em>Jovens Espanh\u00f3is 2021. Ser jovem em tempos de pandemia<\/em><\/a>, nos mostram que h\u00e1 tamb\u00e9m um aumento do n\u00facleo duro de jovens que consideram priorit\u00e1ria a prote\u00e7\u00e3o ao meio ambiente. Na verdade, este \u00e9 provavelmente o dado mais otimista da s\u00e9rie, pois o aumento de jovens que apoiam essa ideia \u00e9 avassalador, passando de 32% em 2005 e 2010 para os 37,1% atuais daqueles que \u201cconcordam totalmente\u201d , e se aproximando de 80% daqueles que pensam assim com maior ou menor intensidade.<\/p>\n<p>No entanto, h\u00e1 uma diferen\u00e7a muito significativa em rela\u00e7\u00e3o ao resto da popula\u00e7\u00e3o espanhola: os jovens parecem estar bastante conscientizados j\u00e1 desde 2005. De fato, basta uma r\u00e1pida olhada na tabela de dados para percebemos imediatamente que, mesmo para algumas perguntas espec\u00edficas, nos encontramos praticamente no mesmo ponto; e de que isso, isso \u00e9 muito interessante, a primeira grande onda de conscientiza\u00e7\u00e3o ambiental provavelmente implicou n\u00e3o um avan\u00e7o, mas um forte retrocesso no caso dos mais jovens. Um forte cansa\u00e7o que nos levou, naquele momento, a propor a hip\u00f3tese de que os jovens consideraram exagerada tamanha campanha de conscientiza\u00e7\u00e3o da noite para o dia, tanto uso e abuso pol\u00edtico ou mesmo comercial, lan\u00e7ando, at\u00e9 mesmo, uma clara advert\u00eancia: \u201cCome\u00e7amos a nos cansar do assunto\u201d (Gonz\u00e1lez-Anleo, 2010, pp. 32-33).<\/p>\n<p>Algo semelhante acontece com a pergunta sobre se o \u201cequil\u00edbrio da natureza \u00e9 forte o bastante para resistir tanto ao impacto dos pa\u00edses desenvolvidos quanto ao dos que est\u00e3o em desenvolvimento\u201d, para a qual h\u00e1 uma diminui\u00e7\u00e3o significativa no conjunto da popula\u00e7\u00e3o jovem, passando de 42% em 2010 para 34,3% em 2020. A percentagem dos que est\u00e3o \u201ctotalmente de acordo\u201d passa de t\u00edmidos 7% em 2005 para 12,7% na atualidade.<\/p>\n<p>A superexposi\u00e7\u00e3o midi\u00e1tica da deteriora\u00e7\u00e3o do meio ambiente conseguiu acabar com o <em>negacionismo<\/em>? Apenas em parte. Ainda h\u00e1 um n\u00facleo duro de <em>negadores<\/em>, 8,3% que afirmam \u201cconcordar muito\u201d com a ideia de que a quest\u00e3o da crise ambiental n\u00e3o passa de um exagero; o mesmo dado, n\u00e3o devemos perder isso de vista, que obt\u00ednhamos em 2005. Porque o <em>negacionismo, c<\/em>omo todas as formas de ideologia, muda para se adaptar. Neste caso, pelo menos em grande medida, o <em>negacionismo<\/em>, que afirmava categoricamente que a crise ambiental n\u00e3o \u00e9 nada mais do que uma inven\u00e7\u00e3o, deu lugar ao que se conhece como <em>neonegacionismo <\/em>que, embora relutantemente, aceita que realmente existe uma crise, mas nega que esta seja produzida pelo homem.<\/p>\n<p>Nesse mesmo estudo, podemos encontrar outro dado de grande relev\u00e2ncia para nossa an\u00e1lise. A Espanha \u00e9 o pa\u00eds da Europa em que a maior propor\u00e7\u00e3o de cidad\u00e3os considera as altera\u00e7\u00f5es clim\u00e1ticas como um fen\u00f3meno \u201crevers\u00edvel\u201d, com apenas 12% que o consideram \u201cirrevers\u00edvel\u201d, sem qualquer nuance. No nosso estudo, esta op\u00e7\u00e3o \u00e9 defendida, com maior ou menor intensidade, por quase um em cada tr\u00eas jovens, com 10,5% deles afirmando que \u201cconcorda totalmente\u201d.<\/p>\n<p>Por outro lado, embora a grande maioria dos jovens, 81% deles, considere que o seu \u201cestilo de vida (consumo, formas de lazer etc.) como cidad\u00e3o de um pa\u00eds desenvolvido \u00e9 importante\u201d, cresce a f\u00e9 na ci\u00eancia e na tecnologia como uma forma de <em>deus ex machina, <\/em>que nos salvar\u00e1 no \u00faltimo momento. Um n\u00e3o argumento ao qual se recorre incansavelmente a partir das fileiras neoliberais para n\u00e3o abrir m\u00e3o do crescimento econ\u00f4mico e dos padr\u00f5es de vida que desfrutamos.<\/p>\n<p>De fato, com a exce\u00e7\u00e3o de uma minoria de jovens, n\u00e3o se penetra no n\u00facleo duro da maioria dos h\u00e1bitos de consumo de \u201calto custo\u201d que analisamos no relat\u00f3rio de 2010 e, embora de fato possa observar uma movimenta\u00e7\u00e3o da juventude neste campo, ainda h\u00e1 muito a ser feito. E o motivo \u00e9 bem simples: o alto consumismo dos jovens, mesmo n\u00e3o trabalhando ou tendo empregos prec\u00e1rios. Uma conclus\u00e3o \u00e0 qual j\u00e1 chegava o relat\u00f3rio da ONU sobre as proje\u00e7\u00f5es dos grandes desafios para 2015, quando destacava que a educa\u00e7\u00e3o ambiental ruim da \u00e9poca colidia com milhares de horas de doutrina\u00e7\u00e3o consumista pelos meios de comunica\u00e7\u00f5es (ONU, 2005). A quest\u00e3o aqui \u00e9 que, mais uma vez, as fortes aspira\u00e7\u00f5es dos jovens colidem frontalmente com seu modo de vida consumista, tornando muito dif\u00edcil para eles atacar quest\u00f5es como o <em>fast mode<\/em>; a obsolesc\u00eancia programada de, por exemplo, celulares e acess\u00f3rios, ou o uso de servi\u00e7os de empresas GAFO; num certo sentido t\u00e3o fortemente enraizadas no quotidiano da juventude que, na pr\u00e1tica, se pode dizer que \u00e9, na atualidade, inerente \u00e0 pr\u00f3pria condi\u00e7\u00e3o de ser jovem. Do que tratamos aqui, portanto, \u00e9 de uma crise no pleno sentido etimol\u00f3gico da palavra, ou seja, do ponto em que h\u00e1 dois caminhos, um que avan\u00e7a para o agravamento do quadro do paciente e outro para a melhora. \u201cUma crise mental\u201d, destacou Ulrich Beck em uma de suas \u00faltimas entrevistas, a de \u201cimaginar a boa vida para al\u00e9m do consumismo\u201d (01\/05\/2014).<\/p>\n<p>Em todos esses dados, surge esbo\u00e7ado um quadro bastante inquietante, na minha opini\u00e3o: um em cada quatro jovens concorda total ou parcialmente que a crise ecol\u00f3gica \u00e9 um exagero; quase um em cada tr\u00eas, considera que o equil\u00edbrio da natureza \u00e9 forte o bastante para suportar o impacto do nosso atual desenvolvimento e, no extremo oposto, quase outro ter\u00e7o deles considera que a batalha j\u00e1 est\u00e1 perdida, portanto, n\u00e3o importa muito o que fa\u00e7amos.<\/p>\n<h2>Bibliografia<\/h2>\n<ul>\n<li>Beck, U. (1\/5\/2014). \u201cLa crisis europea es una crisis mental, es una crisis de c\u00f3mo imaginar la buena vida m\u00e1s all\u00e1 del consumismo\u201d. <em>Ssoci\u00f3logos<\/em>. Disponible en <a href=\"https:\/\/ssociologos.com\/2014\/05\/01\/ulrich-beck-la-crisis-europea-es-una-crisis-mental-es-una-crisis-de-como-imaginar-la-buena-vida-mas-alla-del-consumismo\/\" target=\"_blank\" rel=\"noopener\">https:\/\/ssociologos.com\/2014\/05\/01\/ulrich-beck-la-crisis-europea-es-una-crisis-mental-es-una-crisis-de-como-imaginar-la-buena-vida-mas-alla-del-consumismo\/<\/a>.<\/li>\n<li>European Commission (2020). \u201cSpecial Eurobarometer 501: Attitudes of European citizens towards the Environment\u201d. <em>EU Open Data Portal<\/em>. Disponible en <a href=\"https:\/\/data.europa.eu\/euodp\/en\/data\/dataset\/S2257_92_4_501_ENG\" target=\"_blank\" rel=\"noopener\">https:\/\/data.europa.eu\/euodp\/en\/data\/dataset\/S2257_92_4_501_ENG<\/a>.<\/li>\n<li>Gonz\u00e1lez-Anleo, J. M.\u00aa. (2006). \u201cRelaciones e integraci\u00f3n\u201d. <em>J\u00f3venes espa\u00f1oles 2005<\/em> (pp. 111-184). Madrid: Fundaci\u00f3n SM. Disponible en <a href=\"https:\/\/www.observatoriodelajuventud.org\/jovenes-2005\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.observatoriodelajuventud.org\/jovenes-2005\/<\/a>.<\/li>\n<li>Gonz\u00e1lez-Anleo, J. M.\u00aa. (2010). \u201cLos valores de los j\u00f3venes y su integraci\u00f3n sociopol\u00edtica\u201d. <em>J\u00f3venes espa\u00f1oles 2010<\/em> (pp. 9-113). Madrid: Fundaci\u00f3n SM. Disponible en <a href=\"https:\/\/www.observatoriodelajuventud.org\/jovenes-2010\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.observatoriodelajuventud.org\/jovenes-2010\/<\/a>.<\/li>\n<li>Gonz\u00e1lez-Anleo, J. M.\u00aa. (2020). \u201cValores finales, ecol\u00f3gicos y democr\u00e1ticos, autopercepci\u00f3n y espiritualidad\u201d. <em>J\u00f3venes espa\u00f1oles 2020. Ser joven en tiempos de pandemia<\/em> (pp. 13-80). Madrid: Fundaci\u00f3n SM.<\/li>\n<li>ONU (2005): <em>World Youth Report 2005: Young people today, and in 2015. <\/em>Disponible en <a href=\"https:\/\/www.un.org\/esa\/socdev\/unyin\/documents\/wyr05book.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/www.un.org\/esa\/socdev\/unyin\/documents\/wyr05book.pdf<\/a>.<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3470ab2 elementor-widget elementor-widget-bloque-blog-2\" data-id=\"3470ab2\" data-element_type=\"widget\" data-widget_type=\"bloque-blog-2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n<!-- Bloque Blog -->\n<div class=\"container\">\n    <div class=\"row titulo-con-enlace\">\n        <div class=\"col-12\">\n            <h2 class=\"titulos\" data-aos=\"fade-left\" data-aos-duration=\"700\">Postagens relacionadas<\/h2>                        <a href=\"https:\/\/oes.fundacion-sm.org\/eduforics\/\" data-aos=\"fade-right\" data-aos-duration=\"700\" class=\"enlace btn-arrow\" title=\"Ver mais\"><span>Ver mais<\/span><\/a>\n                    <\/div>\n    <\/div>\n<\/div>\n<section class=\"bloque bloque-blog bloqueqtqbmikmrb  diseno-eduforics \">\n    <div class=\"container\">\n        <div class=\"background  \">\n            <div class=\"estrecho\">\n                <div class=\"row ultimas\">\n                                                            <div class=\"col-12 col-sm-6 d-flex align-items-stretch\" data-aos=\"fade-up\" data-aos-delay=\"200\" data-aos-duration=\"700\">\n                                    <a class=\"noticia \" href=\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/reimaginar-juntos-os-futuros\/escolas-que-cuidam\/entre-memorias-e-geracoes-a-avocidade-na-contemporaneidade\/\">\n    <div class=\"image\">\n        <img fetchpriority=\"high\" decoding=\"async\" width=\"890\" height=\"560\" src=\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/07\/Abuelos-1851810360-890x560.png\" class=\"img-fluid wp-post-image\" alt=\"\" srcset=\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/07\/Abuelos-1851810360-890x560.png 890w, https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/07\/Abuelos-1851810360-300x189.png 300w, https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/07\/Abuelos-1851810360-1024x644.png 1024w, https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/07\/Abuelos-1851810360-768x483.png 768w, https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/07\/Abuelos-1851810360-1056x664.png 1056w, https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/07\/Abuelos-1851810360.png 1200w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/>    <\/div>\n    <div class=\"datos\">\n        <div class=\"categoria\">Escolas que cuidam<\/div>\n        <h3 class=\"subtitulos\">Entre mem\u00f3rias e gera\u00e7\u00f5es: a avosidade na contemporaneidade<\/h3>\n                <div class=\"autor\">Por <em>Maria das Gra\u00e7as Fonseca dos Santos<\/em><\/div>\n            <\/div>\n<\/a>                                    <\/div>\n                                                                    <div class=\"col-12 col-sm-6 d-flex align-items-stretch\" data-aos=\"fade-up\" data-aos-delay=\"500\" data-aos-duration=\"700\">\n                                    <a class=\"noticia \" href=\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/educacao-justica-socioambiental-e-territorios-tradicionais\/\">\n    <div class=\"image\">\n        <img decoding=\"async\" width=\"890\" height=\"560\" src=\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/06\/Brasil-2226192556-890x560.png\" class=\"img-fluid wp-post-image\" alt=\"\" srcset=\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/06\/Brasil-2226192556-890x560.png 890w, https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/06\/Brasil-2226192556-300x189.png 300w, https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/06\/Brasil-2226192556-1024x644.png 1024w, https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/06\/Brasil-2226192556-768x483.png 768w, https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/06\/Brasil-2226192556-1056x664.png 1056w, https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/06\/Brasil-2226192556.png 1200w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/>    <\/div>\n    <div class=\"datos\">\n        <div class=\"categoria\">Educa\u00e7\u00e3o para o desenvolvimento sustent\u00e1vel<\/div>\n        <h3 class=\"subtitulos\">Educa\u00e7\u00e3o, justi\u00e7a socioambiental e territ\u00f3rios tradicionais<\/h3>\n                <div class=\"autor\">Por <em>Equipe de comunica\u00e7\u00e3o do Museu Popular do Horto, Rio de Janeiro<\/em><\/div>\n            <\/div>\n<\/a>                                    <\/div>\n                                                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>O relat\u00f3rio Jovens Espanh\u00f3is 2005 da Funda\u00e7\u00e3o SM foi o pioneiro na introdu\u00e7\u00e3o de uma quest\u00e3o que naquela \u00e9poca parecia importar a muito poucos, mas que hoje, depois de d\u00e9cadas de advert\u00eancias desatendidas das mais altas organiza\u00e7\u00f5es internacionais e ONG ao redor do mundo, acabou ocupando finalmente o centro do cen\u00e1rio sociopol\u00edtico global: os valores [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1139,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[58,36],"tags":[],"class_list":["post-11534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao-desenvolvimento-sustentavel","category-eduforics"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Valores ecol\u00f3gicos entre os jovens. Relat\u00f3rio Jovens Espanh\u00f3is 2021 - Eduforics - Observat\u00f3rio da escola na Ibero-Am\u00e9rica (OES)<\/title>\n<meta name=\"description\" content=\"Os dados do relat\u00f3rio &quot;Jovens espanh\u00f3is 2021&quot; mostram a import\u00e2ncia dos valores ecol\u00f3gicos dos jovens e os valores e a consci\u00eancia ambientais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Valores ecol\u00f3gicos entre os jovens. Relat\u00f3rio Jovens Espanh\u00f3is 2021 - Observat\u00f3rio da escola na Ibero-Am\u00e9rica (OES)\" \/>\n<meta property=\"og:description\" content=\"Os dados do relat\u00f3rio &quot;Jovens espanh\u00f3is 2021&quot; mostram a import\u00e2ncia dos valores ecol\u00f3gicos dos jovens e os valores e a consci\u00eancia ambientais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Observat\u00f3rio da escola na Ibero-Am\u00e9rica (OES)\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-24T09:41:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-20T10:51:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/07\/valoresecologicos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1254\" \/>\n\t<meta property=\"og:image:height\" content=\"836\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ra\u00fal Rockin&#039;Pixels\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ra\u00fal Rockin&#039;Pixels\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/\"},\"author\":{\"name\":\"Ra\u00fal Rockin'Pixels\",\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/#\/schema\/person\/5cb836679a0b57d05045a0d9f8f3116b\"},\"headline\":\"Valores ecol\u00f3gicos entre os jovens. Relat\u00f3rio Jovens Espanh\u00f3is 2021\",\"datePublished\":\"2021-02-24T09:41:00+00:00\",\"dateModified\":\"2023-09-20T10:51:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/\"},\"wordCount\":1529,\"publisher\":{\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/#organization\"},\"image\":{\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/07\/valoresecologicos.jpg\",\"articleSection\":[\"Educa\u00e7\u00e3o para o desenvolvimento sustent\u00e1vel\",\"EDUforics\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/\",\"url\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/\",\"name\":\"Valores ecol\u00f3gicos entre os jovens. Relat\u00f3rio Jovens Espanh\u00f3is 2021 - Observat\u00f3rio da escola na Ibero-Am\u00e9rica (OES)\",\"isPartOf\":{\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/07\/valoresecologicos.jpg\",\"datePublished\":\"2021-02-24T09:41:00+00:00\",\"dateModified\":\"2023-09-20T10:51:31+00:00\",\"description\":\"Os dados do relat\u00f3rio \\\"Jovens espanh\u00f3is 2021\\\" mostram a import\u00e2ncia dos valores ecol\u00f3gicos dos jovens e os valores e a consci\u00eancia ambientais.\",\"breadcrumb\":{\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/#primaryimage\",\"url\":\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/07\/valoresecologicos.jpg\",\"contentUrl\":\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/07\/valoresecologicos.jpg\",\"width\":1254,\"height\":836},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EDUforics\",\"item\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Educa\u00e7\u00e3o inclusiva e de qualidade\",\"item\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Educa\u00e7\u00e3o para o desenvolvimento sustent\u00e1vel\",\"item\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Valores ecol\u00f3gicos entre os jovens. Relat\u00f3rio Jovens Espanh\u00f3is 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/#website\",\"url\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/\",\"name\":\"Observat\u00f3rio da escola na Ibero-Am\u00e9rica (OES)\",\"description\":\"Funda\u00e7\u00e3o SM\",\"publisher\":{\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/#organization\"},\"alternateName\":\"OES\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/#organization\",\"name\":\"Fundaci\u00f3n SM\",\"url\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/10\/logotipo-fundacion-sm.png\",\"contentUrl\":\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/10\/logotipo-fundacion-sm.png\",\"width\":447,\"height\":85,\"caption\":\"Fundaci\u00f3n SM\"},\"image\":{\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/#\/schema\/person\/5cb836679a0b57d05045a0d9f8f3116b\",\"name\":\"Ra\u00fal Rockin'Pixels\",\"sameAs\":[\"https:\/\/fundacion-sm.org\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Valores ecol\u00f3gicos entre os jovens. Relat\u00f3rio Jovens Espanh\u00f3is 2021 - Eduforics - Observat\u00f3rio da escola na Ibero-Am\u00e9rica (OES)","description":"Os dados do relat\u00f3rio \"Jovens espanh\u00f3is 2021\" mostram a import\u00e2ncia dos valores ecol\u00f3gicos dos jovens e os valores e a consci\u00eancia ambientais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/","og_locale":"pt_BR","og_type":"article","og_title":"Valores ecol\u00f3gicos entre os jovens. Relat\u00f3rio Jovens Espanh\u00f3is 2021 - Observat\u00f3rio da escola na Ibero-Am\u00e9rica (OES)","og_description":"Os dados do relat\u00f3rio \"Jovens espanh\u00f3is 2021\" mostram a import\u00e2ncia dos valores ecol\u00f3gicos dos jovens e os valores e a consci\u00eancia ambientais.","og_url":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/","og_site_name":"Observat\u00f3rio da escola na Ibero-Am\u00e9rica (OES)","article_published_time":"2021-02-24T09:41:00+00:00","article_modified_time":"2023-09-20T10:51:31+00:00","og_image":[{"width":1254,"height":836,"url":"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/07\/valoresecologicos.jpg","type":"image\/jpeg"}],"author":"Ra\u00fal Rockin'Pixels","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ra\u00fal Rockin'Pixels","Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/#article","isPartOf":{"@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/"},"author":{"name":"Ra\u00fal Rockin'Pixels","@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/#\/schema\/person\/5cb836679a0b57d05045a0d9f8f3116b"},"headline":"Valores ecol\u00f3gicos entre os jovens. Relat\u00f3rio Jovens Espanh\u00f3is 2021","datePublished":"2021-02-24T09:41:00+00:00","dateModified":"2023-09-20T10:51:31+00:00","mainEntityOfPage":{"@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/"},"wordCount":1529,"publisher":{"@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/#organization"},"image":{"@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/07\/valoresecologicos.jpg","articleSection":["Educa\u00e7\u00e3o para o desenvolvimento sustent\u00e1vel","EDUforics"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/","url":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/","name":"Valores ecol\u00f3gicos entre os jovens. Relat\u00f3rio Jovens Espanh\u00f3is 2021 - Observat\u00f3rio da escola na Ibero-Am\u00e9rica (OES)","isPartOf":{"@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/#primaryimage"},"image":{"@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/07\/valoresecologicos.jpg","datePublished":"2021-02-24T09:41:00+00:00","dateModified":"2023-09-20T10:51:31+00:00","description":"Os dados do relat\u00f3rio \"Jovens espanh\u00f3is 2021\" mostram a import\u00e2ncia dos valores ecol\u00f3gicos dos jovens e os valores e a consci\u00eancia ambientais.","breadcrumb":{"@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/#primaryimage","url":"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/07\/valoresecologicos.jpg","contentUrl":"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/07\/valoresecologicos.jpg","width":1254,"height":836},{"@type":"BreadcrumbList","@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/valores-ecologicos-entre-os-jovens-relatorio-jovens-espanhois-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/oes.fundacion-sm.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"EDUforics","item":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/"},{"@type":"ListItem","position":3,"name":"Educa\u00e7\u00e3o inclusiva e de qualidade","item":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/"},{"@type":"ListItem","position":4,"name":"Educa\u00e7\u00e3o para o desenvolvimento sustent\u00e1vel","item":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/"},{"@type":"ListItem","position":5,"name":"Valores ecol\u00f3gicos entre os jovens. Relat\u00f3rio Jovens Espanh\u00f3is 2021"}]},{"@type":"WebSite","@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/#website","url":"https:\/\/oes.fundacion-sm.org\/pt-br\/","name":"Observat\u00f3rio da escola na Ibero-Am\u00e9rica (OES)","description":"Funda\u00e7\u00e3o SM","publisher":{"@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/#organization"},"alternateName":"OES","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oes.fundacion-sm.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/#organization","name":"Fundaci\u00f3n SM","url":"https:\/\/oes.fundacion-sm.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/10\/logotipo-fundacion-sm.png","contentUrl":"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/10\/logotipo-fundacion-sm.png","width":447,"height":85,"caption":"Fundaci\u00f3n SM"},"image":{"@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/#\/schema\/person\/5cb836679a0b57d05045a0d9f8f3116b","name":"Ra\u00fal Rockin'Pixels","sameAs":["https:\/\/fundacion-sm.org"]}]}},"_links":{"self":[{"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/posts\/11534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/comments?post=11534"}],"version-history":[{"count":17,"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/posts\/11534\/revisions"}],"predecessor-version":[{"id":11553,"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/posts\/11534\/revisions\/11553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/media\/1139"}],"wp:attachment":[{"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/media?parent=11534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/categories?post=11534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/tags?post=11534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}