{"id":9639,"date":"2020-03-27T09:02:00","date_gmt":"2020-03-27T08:02:00","guid":{"rendered":"https:\/\/oes.fundacion-sm.org\/noticias\/guias-ensenan-a-los-ninos-y-adolescentes-a-lidiar-con-el-covid-19\/"},"modified":"2023-09-14T16:56:10","modified_gmt":"2023-09-14T14:56:10","slug":"guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19","status":"publish","type":"post","link":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/","title":{"rendered":"Guias ensinam crian\u00e7as e adolescentes a lidar com o COVID-19"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9639\" class=\"elementor elementor-9639 elementor-5767\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-114af4ec elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"114af4ec\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-189eeaca\" data-id=\"189eeaca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ca1b00c elementor-widget elementor-widget-bloque-texto\" data-id=\"5ca1b00c\" data-element_type=\"widget\" data-widget_type=\"bloque-texto.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- Texto -->\n<section class=\"bloque bloque-texto  \">\n    <div class=\"container\">\n        <div class=\"estrecho2\">\n            \n            <div class=\"row\">\n                <div class=\"col-sm-12\">\n                    <div class=\"the_content\" data-aos=\"fade-up\" data-aos-duration=\"700\">\n                        <p>Em meio \u00e0 pandemia do coronav\u00edrus (COVID-19), que levou pessoas do mundo inteiro a fazer isolamento social para conter a prolifera\u00e7\u00e3o da doen\u00e7a que j\u00e1 causou mais de 23 mil mortes at\u00e9 o momento, muita informa\u00e7\u00e3o circula numa velocidade t\u00e3o grande que fica dif\u00edcil distinguir quais s\u00e3o verdadeiras ou falsas. Ao mesmo tempo, crian\u00e7as e adolescentes tiveram as aulas suspensas e suas rotinas completamente alteradas de uma hora para outra. Como explicar para eles como e porque isso aconteceu, al\u00e9m de dar uma perspectiva de como ser\u00e1 o processo at\u00e9 que a rotina escolar seja retomada.<\/p>\n<p>Foi pensando nisso que a Campanha Nacional pelo Direito \u00e0 Educa\u00e7\u00e3o e a plataforma Cada Crian\u00e7a lan\u00e7aram o \u201cGuia COVID-19 \u2013 Educa\u00e7\u00e3o e Prote\u00e7\u00e3o de crian\u00e7as e adolescentes\u201d com o objetivo de oferecer um compilado de informa\u00e7\u00f5es checadas, comprovadas e acess\u00edveis sobre como cidad\u00e3os ligados \u00e0 educa\u00e7\u00e3o podem agir, cobrar, e trabalhar pela prote\u00e7\u00e3o de todos de maneira colaborativa.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b81f60c elementor-widget elementor-widget-bloque-imagen-articulo\" data-id=\"b81f60c\" data-element_type=\"widget\" data-widget_type=\"bloque-imagen-articulo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- Texto -->\n<section class=\"bloque bloque-texto  \">\n    <div class=\"container\">\n        <div class=\"estrecho2\">\n                        <div class=\"row\">\n                <div class=\"col-sm-12\">\n                    <div class=\"the_content\" data-aos=\"fade-up\" data-aos-duration=\"700\">\n                        <figure class=\"figure imagen2 imagen-centrada\">\n                            <div class=\"image\">\n                                                                <img decoding=\"async\" src=\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2020\/03\/guia-1-covid-19-capa.jpg\" class=\"figure-img img-fluid\" alt=\"\">\n                                                                <\/a>\n                                \n                                                                <figcaption class=\"figure-caption\">Guia COVID-19 \u2013 Educa\u00e7\u00e3o e Prote\u00e7\u00e3o de crian\u00e7as e adolescentes<\/figcaption>\n                                                            <\/div>\n                        <\/figure>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef6ea1e elementor-widget elementor-widget-bloque-texto\" data-id=\"ef6ea1e\" data-element_type=\"widget\" data-widget_type=\"bloque-texto.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- Texto -->\n<section class=\"bloque bloque-texto  \">\n    <div class=\"container\">\n        <div class=\"estrecho2\">\n            \n            <div class=\"row\">\n                <div class=\"col-sm-12\">\n                    <div class=\"the_content\" data-aos=\"fade-up\" data-aos-duration=\"700\">\n                        <p>O material est\u00e1 dividido em dois volumes:<\/p>\n<p><strong>Volume 1: <\/strong>destinado \u00e0 comunidade escolar (professores, diretores e profissionais da educa\u00e7\u00e3o), fam\u00edlia (m\u00e3es, pais, respons\u00e1veis, tias, tios, primas, primos, av\u00f3s, irm\u00e3s e irm\u00e3os mais velhos) e assistentes sociais e demais profissionais da prote\u00e7\u00e3o da crian\u00e7a e do adolescente.<\/p>\n<p>Nele, o leitor pode encontrar orienta\u00e7\u00f5es que explicam t\u00f3picos como:<\/p>\n<ul>\n<li>Por que fechar as escolas? Por que o necess\u00e1rio isolamento social \u00e9 necess\u00e1rio? Quais os efeitos disso \u00e0 popula\u00e7\u00e3o;<\/li>\n<li>A situa\u00e7\u00e3o no Brasil e no mundo sobre a suspens\u00e3o de aulas em n\u00fameros e mapas;<\/li>\n<li>O que fazer diante do problema geral: saber formas de pressionar por mais recursos para as \u00e1reas de sa\u00fade, assist\u00eancia, seguran\u00e7a alimentar e educa\u00e7\u00e3o, e seguir medidas preventivas indicadas pelas autoridades p\u00fablicas;<\/li>\n<li>O que fazer com rela\u00e7\u00e3o \u00e0s escolas que ainda n\u00e3o fecharam;<\/li>\n<li>De que maneira a educa\u00e7\u00e3o a dist\u00e2ncia (EaD), se for considerada atividade regular e contada nos dias letivos, deve ampliar as desigualdades educacionais e sociais?<\/li>\n<li>Como reivindicar provid\u00eancias a realiza\u00e7\u00e3o de atividades complementares virtualmente e a flexibiliza\u00e7\u00e3o do cumprimento dos 200 dias letivos;<\/li>\n<li>Dicas do que fazer com as crian\u00e7as e os adolescentes em casa;<\/li>\n<li>O que fazer para exigir o direito \u00e0 alimenta\u00e7\u00e3o escolar.<\/li>\n<\/ul>\n<p>J\u00e1 o <strong>Volume 2<\/strong> foi pensado para orientar tomadores de decis\u00e3o do poder p\u00fablico e apresentar possibilidades de financiamento, garantia de direitos, suspens\u00e3o das aulas e ao Ensino a Dist\u00e2ncia. O guia aborda os seguintes temas:<\/p>\n<ul>\n<li>A necessidade de suspens\u00e3o da Emenda Constitucional 95\/2016 (Teto de Gastos), uma vez que ela n\u00e3o \u00e9 poss\u00edvel garantir sa\u00fade e educa\u00e7\u00e3o, pois h\u00e1 tr\u00eas anos existe a redu\u00e7\u00e3o de financiamento nessas \u00e1reas, fragilizando a capacidade do Estado em dar respostas adequadas a emerg\u00eancias como a do coronav\u00edrus;<\/li>\n<li>A recomenda\u00e7\u00e3o da cria\u00e7\u00e3o de um Fundo de Emerg\u00eancia em Defesa do Trabalho e Renda. Prop\u00f5e condi\u00e7\u00f5es para oferecer uma renda b\u00e1sica de emerg\u00eancia mensal, baseando-se na iniciativa de entidades que aderem ao <a href=\"https:\/\/rendabasica.org.br\/\" target=\"_blank\" rel=\"noopener\">rendabasica.org.br<\/a>;<\/li>\n<li>O que fazer durante o per\u00edodo de suspens\u00e3o das aulas, lidando com corpo docente, funcion\u00e1rios e as fam\u00edlias das crian\u00e7as;<\/li>\n<li>Como lidar com a falta de infraestrutura tecnol\u00f3gica para implementar o Ensino a Dist\u00e2ncia (EaD).<\/li>\n<\/ul>\n<p>Ambos os guias est\u00e3o dispon\u00edveis para download gratuitamente:<\/p>\n<p><a class=\"enlace btn-arrow d-block\" href=\"https:\/\/media.campanha.org.br\/acervo\/documentos\/COVID-19_Guia1_FINAL.pdf\" target=\"_blank\" rel=\"noopener\">Educa\u00e7\u00e3o e Prote\u00e7\u00e3o de crian\u00e7as e adolescentes \u2013 Volume 1<\/a><\/p>\n<p><a class=\"enlace btn-arrow d-block\" href=\"https:\/\/media.campanha.org.br\/acervo\/documentos\/COVID-19_Guia2_FINAL.pdf\" target=\"_blank\" rel=\"noopener\">Educa\u00e7\u00e3o e Prote\u00e7\u00e3o de crian\u00e7as e adolescentes \u2013 Volume 2<\/a><\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55e9e197 elementor-widget elementor-widget-bloque-blog-2\" data-id=\"55e9e197\" data-element_type=\"widget\" data-widget_type=\"bloque-blog-2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n<!-- Bloque Blog -->\n<div class=\"container\">\n    <div class=\"row titulo-con-enlace\">\n        <div class=\"col-12\">\n            <h2 class=\"titulos\" data-aos=\"fade-left\" data-aos-duration=\"700\">Postagens relacionadas<\/h2>                        <a href=\"https:\/\/oes.fundacion-sm.org\/eduforics\/\" data-aos=\"fade-right\" data-aos-duration=\"700\" class=\"enlace btn-arrow\" title=\"Ver mais\"><span>Ver mais<\/span><\/a>\n                    <\/div>\n    <\/div>\n<\/div>\n<section class=\"bloque bloque-blog bloquetiulxkpqrx  diseno-eduforics \">\n    <div class=\"container\">\n        <div class=\"background  \">\n            <div class=\"estrecho\">\n                <div class=\"row ultimas\">\n                                                            <div class=\"col-12 col-sm-6 d-flex align-items-stretch\" data-aos=\"fade-up\" data-aos-delay=\"200\" data-aos-duration=\"700\">\n                                    <a class=\"noticia \" href=\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/reimaginar-juntos-os-futuros\/escolas-que-cuidam\/entre-memorias-e-geracoes-a-avocidade-na-contemporaneidade\/\">\n    <div class=\"image\">\n        <img fetchpriority=\"high\" decoding=\"async\" width=\"890\" height=\"560\" src=\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/07\/Abuelos-1851810360-890x560.png\" class=\"img-fluid wp-post-image\" alt=\"\" srcset=\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/07\/Abuelos-1851810360-890x560.png 890w, https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/07\/Abuelos-1851810360-300x189.png 300w, https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/07\/Abuelos-1851810360-1024x644.png 1024w, https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/07\/Abuelos-1851810360-768x483.png 768w, https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/07\/Abuelos-1851810360-1056x664.png 1056w, https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/07\/Abuelos-1851810360.png 1200w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/>    <\/div>\n    <div class=\"datos\">\n        <div class=\"categoria\">Escolas que cuidam<\/div>\n        <h3 class=\"subtitulos\">Entre mem\u00f3rias e gera\u00e7\u00f5es: a avosidade na contemporaneidade<\/h3>\n                <div class=\"autor\">Por <em>Maria das Gra\u00e7as Fonseca dos Santos<\/em><\/div>\n            <\/div>\n<\/a>                                    <\/div>\n                                                                    <div class=\"col-12 col-sm-6 d-flex align-items-stretch\" data-aos=\"fade-up\" data-aos-delay=\"500\" data-aos-duration=\"700\">\n                                    <a class=\"noticia \" href=\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/educacao-justica-socioambiental-e-territorios-tradicionais\/\">\n    <div class=\"image\">\n        <img decoding=\"async\" width=\"890\" height=\"560\" src=\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/06\/Brasil-2226192556-890x560.png\" class=\"img-fluid wp-post-image\" alt=\"\" srcset=\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/06\/Brasil-2226192556-890x560.png 890w, https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/06\/Brasil-2226192556-300x189.png 300w, https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/06\/Brasil-2226192556-1024x644.png 1024w, https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/06\/Brasil-2226192556-768x483.png 768w, https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/06\/Brasil-2226192556-1056x664.png 1056w, https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2026\/06\/Brasil-2226192556.png 1200w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/>    <\/div>\n    <div class=\"datos\">\n        <div class=\"categoria\">Educa\u00e7\u00e3o para o desenvolvimento sustent\u00e1vel<\/div>\n        <h3 class=\"subtitulos\">Educa\u00e7\u00e3o, justi\u00e7a socioambiental e territ\u00f3rios tradicionais<\/h3>\n                <div class=\"autor\">Por <em>Equipe de comunica\u00e7\u00e3o do Museu Popular do Horto, Rio de Janeiro<\/em><\/div>\n            <\/div>\n<\/a>                                    <\/div>\n                                                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Em meio \u00e0 pandemia do coronav\u00edrus (COVID-19), que levou pessoas do mundo inteiro a fazer isolamento social para conter a prolifera\u00e7\u00e3o da doen\u00e7a que j\u00e1 causou mais de 23 mil mortes at\u00e9 o momento, muita informa\u00e7\u00e3o circula numa velocidade t\u00e3o grande que fica dif\u00edcil distinguir quais s\u00e3o verdadeiras ou falsas. Ao mesmo tempo, crian\u00e7as e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5769,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[58,36],"tags":[],"class_list":["post-9639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao-desenvolvimento-sustentavel","category-eduforics"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Guias ensinam crian\u00e7as e adolescentes a lidar com o COVID-19 - Eduforics - Observat\u00f3rio da escola na Ibero-Am\u00e9rica (OES)<\/title>\n<meta name=\"description\" content=\"A pandemia do coronav\u00edrus (COVID-19) levou ao isolamento social. Crian\u00e7as e adolescentes tiveram suas aulas suspensas e suas rotinas alteradas repentinamente. Como explicar a eles como e por que isso aconteceu?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guias ensinam crian\u00e7as e adolescentes a lidar com o COVID-19 - Observat\u00f3rio da escola na Ibero-Am\u00e9rica (OES)\" \/>\n<meta property=\"og:description\" content=\"A pandemia do coronav\u00edrus (COVID-19) levou ao isolamento social. Crian\u00e7as e adolescentes tiveram suas aulas suspensas e suas rotinas alteradas repentinamente. Como explicar a eles como e por que isso aconteceu?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Observat\u00f3rio da escola na Ibero-Am\u00e9rica (OES)\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-27T08:02:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-14T14:56:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/08\/guia-covid-19-portada.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1056\" \/>\n\t<meta property=\"og:image:height\" content=\"664\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Antonio Rockin&#039;Pixels\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Rockin&#039;Pixels\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/\"},\"author\":{\"name\":\"Antonio Rockin'Pixels\",\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/#\/schema\/person\/853f955beb537b852c3687d514f42948\"},\"headline\":\"Guias ensinam crian\u00e7as e adolescentes a lidar com o COVID-19\",\"datePublished\":\"2020-03-27T08:02:00+00:00\",\"dateModified\":\"2023-09-14T14:56:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/\"},\"wordCount\":682,\"publisher\":{\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/#organization\"},\"image\":{\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/08\/guia-covid-19-portada.png\",\"articleSection\":[\"Educa\u00e7\u00e3o para o desenvolvimento sustent\u00e1vel\",\"EDUforics\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/\",\"url\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/\",\"name\":\"Guias ensinam crian\u00e7as e adolescentes a lidar com o COVID-19 - Observat\u00f3rio da escola na Ibero-Am\u00e9rica (OES)\",\"isPartOf\":{\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/08\/guia-covid-19-portada.png\",\"datePublished\":\"2020-03-27T08:02:00+00:00\",\"dateModified\":\"2023-09-14T14:56:10+00:00\",\"description\":\"A pandemia do coronav\u00edrus (COVID-19) levou ao isolamento social. Crian\u00e7as e adolescentes tiveram suas aulas suspensas e suas rotinas alteradas repentinamente. Como explicar a eles como e por que isso aconteceu?\",\"breadcrumb\":{\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/#primaryimage\",\"url\":\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/08\/guia-covid-19-portada.png\",\"contentUrl\":\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/08\/guia-covid-19-portada.png\",\"width\":1056,\"height\":664},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EDUforics\",\"item\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Educa\u00e7\u00e3o inclusiva e de qualidade\",\"item\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Educa\u00e7\u00e3o para o desenvolvimento sustent\u00e1vel\",\"item\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Guias ensinam crian\u00e7as e adolescentes a lidar com o COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/#website\",\"url\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/\",\"name\":\"Observat\u00f3rio da escola na Ibero-Am\u00e9rica (OES)\",\"description\":\"Funda\u00e7\u00e3o SM\",\"publisher\":{\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/#organization\"},\"alternateName\":\"OES\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/#organization\",\"name\":\"Fundaci\u00f3n SM\",\"url\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/10\/logotipo-fundacion-sm.png\",\"contentUrl\":\"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/10\/logotipo-fundacion-sm.png\",\"width\":447,\"height\":85,\"caption\":\"Fundaci\u00f3n SM\"},\"image\":{\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/oes.fundacion-sm.org\/pt-br\/#\/schema\/person\/853f955beb537b852c3687d514f42948\",\"name\":\"Antonio Rockin'Pixels\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guias ensinam crian\u00e7as e adolescentes a lidar com o COVID-19 - Eduforics - Observat\u00f3rio da escola na Ibero-Am\u00e9rica (OES)","description":"A pandemia do coronav\u00edrus (COVID-19) levou ao isolamento social. Crian\u00e7as e adolescentes tiveram suas aulas suspensas e suas rotinas alteradas repentinamente. Como explicar a eles como e por que isso aconteceu?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/","og_locale":"pt_BR","og_type":"article","og_title":"Guias ensinam crian\u00e7as e adolescentes a lidar com o COVID-19 - Observat\u00f3rio da escola na Ibero-Am\u00e9rica (OES)","og_description":"A pandemia do coronav\u00edrus (COVID-19) levou ao isolamento social. Crian\u00e7as e adolescentes tiveram suas aulas suspensas e suas rotinas alteradas repentinamente. Como explicar a eles como e por que isso aconteceu?","og_url":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/","og_site_name":"Observat\u00f3rio da escola na Ibero-Am\u00e9rica (OES)","article_published_time":"2020-03-27T08:02:00+00:00","article_modified_time":"2023-09-14T14:56:10+00:00","og_image":[{"width":1056,"height":664,"url":"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/08\/guia-covid-19-portada.png","type":"image\/png"}],"author":"Antonio Rockin'Pixels","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Rockin'Pixels","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/#article","isPartOf":{"@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/"},"author":{"name":"Antonio Rockin'Pixels","@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/#\/schema\/person\/853f955beb537b852c3687d514f42948"},"headline":"Guias ensinam crian\u00e7as e adolescentes a lidar com o COVID-19","datePublished":"2020-03-27T08:02:00+00:00","dateModified":"2023-09-14T14:56:10+00:00","mainEntityOfPage":{"@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/"},"wordCount":682,"publisher":{"@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/#organization"},"image":{"@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/08\/guia-covid-19-portada.png","articleSection":["Educa\u00e7\u00e3o para o desenvolvimento sustent\u00e1vel","EDUforics"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/","url":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/","name":"Guias ensinam crian\u00e7as e adolescentes a lidar com o COVID-19 - Observat\u00f3rio da escola na Ibero-Am\u00e9rica (OES)","isPartOf":{"@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/08\/guia-covid-19-portada.png","datePublished":"2020-03-27T08:02:00+00:00","dateModified":"2023-09-14T14:56:10+00:00","description":"A pandemia do coronav\u00edrus (COVID-19) levou ao isolamento social. Crian\u00e7as e adolescentes tiveram suas aulas suspensas e suas rotinas alteradas repentinamente. Como explicar a eles como e por que isso aconteceu?","breadcrumb":{"@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/#primaryimage","url":"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/08\/guia-covid-19-portada.png","contentUrl":"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/08\/guia-covid-19-portada.png","width":1056,"height":664},{"@type":"BreadcrumbList","@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/guias-ensinam-criancas-e-adolescentes-a-lidar-com-o-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/oes.fundacion-sm.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"EDUforics","item":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/"},{"@type":"ListItem","position":3,"name":"Educa\u00e7\u00e3o inclusiva e de qualidade","item":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/"},{"@type":"ListItem","position":4,"name":"Educa\u00e7\u00e3o para o desenvolvimento sustent\u00e1vel","item":"https:\/\/oes.fundacion-sm.org\/pt-br\/eduforics\/educacao-inclusiva-e-de-qualidade\/educacao-desenvolvimento-sustentavel\/"},{"@type":"ListItem","position":5,"name":"Guias ensinam crian\u00e7as e adolescentes a lidar com o COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/#website","url":"https:\/\/oes.fundacion-sm.org\/pt-br\/","name":"Observat\u00f3rio da escola na Ibero-Am\u00e9rica (OES)","description":"Funda\u00e7\u00e3o SM","publisher":{"@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/#organization"},"alternateName":"OES","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oes.fundacion-sm.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/#organization","name":"Fundaci\u00f3n SM","url":"https:\/\/oes.fundacion-sm.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/10\/logotipo-fundacion-sm.png","contentUrl":"https:\/\/oes.fundacion-sm.org\/wp-content\/uploads\/sites\/14\/2023\/10\/logotipo-fundacion-sm.png","width":447,"height":85,"caption":"Fundaci\u00f3n SM"},"image":{"@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/oes.fundacion-sm.org\/pt-br\/#\/schema\/person\/853f955beb537b852c3687d514f42948","name":"Antonio Rockin'Pixels"}]}},"_links":{"self":[{"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/posts\/9639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/comments?post=9639"}],"version-history":[{"count":11,"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/posts\/9639\/revisions"}],"predecessor-version":[{"id":9651,"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/posts\/9639\/revisions\/9651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/media\/5769"}],"wp:attachment":[{"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/media?parent=9639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/categories?post=9639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oes.fundacion-sm.org\/pt-br\/wp-json\/wp\/v2\/tags?post=9639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}